{"id":14257,"date":"2026-05-07T14:54:25","date_gmt":"2026-05-07T12:54:25","guid":{"rendered":"https:\/\/www.cbd.fr\/blog\/?p=14257"},"modified":"2026-05-07T14:54:25","modified_gmt":"2026-05-07T12:54:25","slug":"quelle-est-la-difference-entre-le-chanvre-et-le-cannabis","status":"publish","type":"post","link":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/","title":{"rendered":"Quelle est la diff\u00e9rence entre le chanvre et le cannabis ?"},"content":{"rendered":"<p>La confusion persiste souvent entre <strong>le chanvre<\/strong> et <strong>le cannabis<\/strong>. Pourtant, derri\u00e8re ces deux noms se cachent des r\u00e9alit\u00e9s botaniques, culturelles et juridiques bien distinctes. Pour mieux comprendre ce qui s\u00e9pare vraiment ces deux plantes apparent\u00e9es, il faut plonger dans leurs <strong>caract\u00e9ristiques<\/strong>, leurs usages, leur <strong>teneur en <a href=\"https:\/\/www.cbd.fr\/198thccbd\" data-internallinksmanager029f6b8e52c=\"17\" title=\"thc - t\u00e9trahydrocannabinol\">THC<\/a><\/strong> ainsi que les subtilit\u00e9s de la <strong>l\u00e9galit\u00e9<\/strong> et de la r\u00e9glementation en vigueur. D\u00e9cryptage complet pour lever le voile sur leurs points communs et leurs diff\u00e9rences fondamentales.<\/p>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Comprendre_lorigine_botanique_cannabis_sativa_et_ses_sous-especes\" >Comprendre l\u2019origine botanique : cannabis sativa et ses sous-esp\u00e8ces<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Le_role_des_cannabinoides\" >Le r\u00f4le des cannabino\u00efdes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Differenciation_morphologique_et_agricole\" >Diff\u00e9renciation morphologique et agricole<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Teneur_en_THC_facteur_determinant_entre_usage_industriel_et_recreatif\" >Teneur en THC : facteur d\u00e9terminant entre usage industriel et r\u00e9cr\u00e9atif<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Impact_sur_la_legalitereglementation\" >Impact sur la l\u00e9galit\u00e9\/r\u00e9glementation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Liste_comparative_des_differences_majeures\" >Liste comparative des diff\u00e9rences majeures<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Usages_de_la_plante_quelles_sont_les_applications_principales\" >Usages de la plante : quelles sont les applications principales ?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Applications_industrielles_vs_usages_recreatifs\" >Applications industrielles vs usages r\u00e9cr\u00e9atifs<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Tableau_comparatif_dusages\" >Tableau comparatif d\u2019usages<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Questions_frequemment_posees_sur_la_difference_entre_chanvre_et_cannabis\" >Questions fr\u00e9quemment pos\u00e9es sur la diff\u00e9rence entre chanvre et cannabis<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Le_chanvre_est-il_legal_partout\" >Le chanvre est-il l\u00e9gal partout ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Est-ce_que_le_chanvre_contient_du_CBD\" >Est-ce que le chanvre contient du CBD ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Pourquoi_utilise-t-on_le_terme_chanvre_industriel\" >Pourquoi utilise-t-on le terme chanvre industriel ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#Comment_differencier_visuellement_le_chanvre_du_cannabis_recreatif\" >Comment diff\u00e9rencier visuellement le chanvre du cannabis r\u00e9cr\u00e9atif ?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Comprendre_lorigine_botanique_cannabis_sativa_et_ses_sous-especes\"><\/span>Comprendre l\u2019origine botanique : cannabis sativa et ses sous-esp\u00e8ces<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>D\u2019un point de vue botanique, <strong>chanvre<\/strong> et <strong>cannabis<\/strong> font tous deux partie de la grande famille du <strong>cannabis sativa<\/strong>. Cette plante historique aux multiples usages se d\u00e9cline en plusieurs vari\u00e9t\u00e9s, chacune pr\u00e9sentant des profils chimiques et morphologiques bien sp\u00e9cifiques.<\/p>\n<p>Les diff\u00e9rences notables r\u00e9sident surtout dans la s\u00e9lection g\u00e9n\u00e9tique op\u00e9r\u00e9e par l\u2019homme au fil du temps. Alors que certaines lign\u00e9es ont \u00e9t\u00e9 d\u00e9velopp\u00e9es pour leurs <strong>fibres robustes<\/strong> ou leurs <strong>graines riches en <a href=\"https:\/\/www.cbd.fr\/84huiles-de-cbd\" data-internallinksmanager029f6b8e52c=\"3\" title=\"Huile CBD\">huile<\/a><\/strong>, d\u2019autres l\u2019ont \u00e9t\u00e9 pour une <a href=\"https:\/\/www.cbd.fr\/blog\/quelles-differences-entre-le-thc-delta-8-et-le-thc-delta-9\/\">teneur \u00e9lev\u00e9e en substances psychoactives<\/a>, principalement le t\u00e9trahydrocannabinol (<strong>THC<\/strong>).<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"Le_role_des_cannabinoides\"><\/span>Le r\u00f4le des cannabino\u00efdes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Parmi les centaines de compos\u00e9s pr\u00e9sents dans le <strong>cannabis sativa<\/strong>, ce sont surtout le <strong>THC<\/strong> et le <strong>cannabidiol (CBD)<\/strong> qui attirent l\u2019attention. Le premier provoque un <strong>effet planant<\/strong>, recherch\u00e9 dans l\u2019usage r\u00e9cr\u00e9atif, tandis que le second s\u00e9duit par ses applications bien-\u00eatre sans induire d\u2019alt\u00e9ration de la perception.<\/p>\n<p>La pr\u00e9sence de ces mol\u00e9cules varie consid\u00e9rablement selon les <strong>sous-esp\u00e8ces<\/strong> et les cultures sp\u00e9cifiques. C\u2019est justement ce qui permet de tracer une fronti\u00e8re claire entre le <strong>chanvre industriel<\/strong> et le <strong>chanvre r\u00e9cr\u00e9atif<\/strong>.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"Differenciation_morphologique_et_agricole\"><\/span>Diff\u00e9renciation morphologique et agricole<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le <strong>chanvre industriel<\/strong> se caract\u00e9rise par une croissance rapide, une tige longue et fine ainsi qu\u2019une faible densit\u00e9 de glandes r\u00e9sineuses. Cette morphologie facilite <strong>l\u2019extraction<\/strong> depuis divers organes de la plante comme les graines, les tiges, les fleurs ou les feuilles, adapt\u00e9s \u00e0 diff\u00e9rents usages.<\/p>\n<p>Le <strong>cannabis utilis\u00e9 \u00e0 des fins r\u00e9cr\u00e9atives<\/strong> pr\u00e9sente quant \u00e0 lui des plants plus compacts, fortement ramifi\u00e9s et couverts de <strong>trichomes r\u00e9sineux<\/strong> responsables de la concentration en THC et autres cannabino\u00efdes.<\/p>\n\n<h2><span class=\"ez-toc-section\" id=\"Teneur_en_THC_facteur_determinant_entre_usage_industriel_et_recreatif\"><\/span>Teneur en THC : facteur d\u00e9terminant entre usage industriel et r\u00e9cr\u00e9atif<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le <strong>seuil l\u00e9gal de THC<\/strong> reste le crit\u00e8re principal pour distinguer le chanvre du <strong>cannabis dit r\u00e9cr\u00e9atif<\/strong>. Dans presque tous les pays, la l\u00e9gislation impose une limite maximale de cette mol\u00e9cule pour autoriser la culture et la commercialisation du <strong>chanvre<\/strong>.<\/p>\n<p>On distingue \u00e9galement diff\u00e9rentes formes de mol\u00e9cules comme le THC Delta 8 et Delta 9 pr\u00e9sentes dans les fleurs de cannabis, qui pr\u00e9sentent chacune des concentrations variables selon les vari\u00e9t\u00e9s. Pour approfondir ce sujet, vous pouvez consulter un dossier complet sur la <a href=\"https:\/\/www.cbd.fr\/blog\/quelles-differences-entre-le-thc-delta-8-et-le-thc-delta-9\/\">diff\u00e9rence entre le THC Delta 8 et Delta 9<\/a>.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"Impact_sur_la_legalitereglementation\"><\/span>Impact sur la l\u00e9galit\u00e9\/r\u00e9glementation<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ce plafond r\u00e9glementaire implique une surveillance \u00e9troite de la <strong>teneur en THC<\/strong> dans toutes les cultures d\u00e9clar\u00e9es comme <strong>chanvre industriel<\/strong>. Seules les <strong>vari\u00e9t\u00e9s certifi\u00e9es<\/strong>, r\u00e9pondant \u00e0 ces crit\u00e8res stricts, peuvent entrer dans la cha\u00eene de production du textile, du bien-\u00eatre ou de l\u2019alimentation.<\/p>\n<p>Le non-respect du seuil fait automatiquement basculer la plante dans la cat\u00e9gorie du <strong>cannabis r\u00e9cr\u00e9atif<\/strong>, soumis \u00e0 une l\u00e9gislation nettement plus s\u00e9v\u00e8re. La d\u00e9tention, la vente ou la culture deviennent alors passibles de sanctions p\u00e9nales dans la majorit\u00e9 des pays europ\u00e9ens.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"Liste_comparative_des_differences_majeures\"><\/span>Liste comparative des diff\u00e9rences majeures<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n  <li><strong>Origine botanique :<\/strong> Chanvre et cannabis appartiennent \u00e0 la m\u00eame esp\u00e8ce mais diff\u00e8rent par la vari\u00e9t\u00e9 et la s\u00e9lection appliqu\u00e9e.<\/li>\n  <li><strong>Teneur en THC :<\/strong> Chanvre \u2264 0,3 % ; Cannabis r\u00e9cr\u00e9atif peut d\u00e9passer 20 % de THC.<\/li>\n  <li><strong>Usage :<\/strong> Chanvre destin\u00e9 \u00e0 l\u2019industrie, \u00e0 la nutrition et au bien-\u00eatre ; cannabis r\u00e9cr\u00e9atif utilis\u00e9 pour sa capacit\u00e9 \u00e0 provoquer un effet planant.<\/li>\n  <li><strong>Extraction :<\/strong> Chanvre utilis\u00e9 dans la valorisation des tiges\/fibres, graines ; cannabis r\u00e9cr\u00e9atif valoris\u00e9 pour ses fleurs riches en r\u00e9sines.<\/li>\n  <li><strong>L\u00e9galit\u00e9\/r\u00e9glementation :<\/strong> Diff\u00e9rences tr\u00e8s nettes entre les deux segments encadr\u00e9es par la loi.<\/li>\n<\/ul>\n\n<h2><span class=\"ez-toc-section\" id=\"Usages_de_la_plante_quelles_sont_les_applications_principales\"><\/span>Usages de la plante : quelles sont les applications principales ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les divergences fondamentales entre <strong>chanvre industriel<\/strong> et <strong>cannabis r\u00e9cr\u00e9atif<\/strong> se manifestent avant tout dans les d\u00e9bouch\u00e9s et utilisations concr\u00e8tes de chaque plante. Le spectre des <strong>applications<\/strong> est extr\u00eamement large pour le chanvre.<\/p>\n<p>Exploit\u00e9 depuis des mill\u00e9naires, le <strong>chanvre<\/strong> est cultiv\u00e9 pour la fabrication de <strong>textiles<\/strong>, de cordages, pour l\u2019extraction d\u2019<strong>huile alimentaire<\/strong> riche en om\u00e9ga-3 et prot\u00e9ines, mais aussi comme source principale du <strong>CBD<\/strong> pr\u00e9sent dans de nombreux produits de bien-\u00eatre.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"Applications_industrielles_vs_usages_recreatifs\"><\/span>Applications industrielles vs usages r\u00e9cr\u00e9atifs<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Le <strong>chanvre industriel<\/strong> s\u2019invite aujourd\u2019hui dans la construction (b\u00e9ton de chanvre), dans l\u2019automobile (biosourc\u00e9) et dans la papeterie. Ses <strong>graines<\/strong> offrent des compl\u00e9ments alimentaires pris\u00e9s pour leurs nutriments tandis que ses <strong>fleurs et feuilles<\/strong> servent de base \u00e0 l\u2019extraction du <strong>cannabidiol<\/strong>, un atout phare pour la cosm\u00e9tique et les compl\u00e9ments naturels.<\/p>\n<p>A contrario, le <strong>cannabis r\u00e9cr\u00e9atif<\/strong> est essentiellement cultiv\u00e9 pour ses <strong>effets psychotropes<\/strong> gr\u00e2ce \u00e0 une haute teneur en THC. Les consommateurs recherchent alors l&#8217;effet planant associ\u00e9 \u00e0 cette vari\u00e9t\u00e9 sp\u00e9cifique.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"Tableau_comparatif_dusages\"><\/span>Tableau comparatif d\u2019usages<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<table>\n  <tr>\n    <th>Chanvre industriel<\/th>\n    <th>Cannabis r\u00e9cr\u00e9atif<\/th>\n  <\/tr>\n  <tr>\n    <td>Textiles, cordages, papier<\/td>\n    <td>Consommation fum\u00e9e\/vaporis\u00e9e<\/td>\n  <\/tr>\n  <tr>\n    <td>Huile v\u00e9g\u00e9tale comestible<br>Prot\u00e9ines alimentaires<\/td>\n    <td>Recherche de l&#8217;effet planant<\/td>\n  <\/tr>\n  <tr>\n    <td>Compl\u00e9ments alimentaires (CBD)<\/td>\n    <td>Extraction de THC ou d&#8217;autres cannabino\u00efdes psychoactifs<\/td>\n  <\/tr>\n  <tr>\n    <td>Cosm\u00e9tique, mat\u00e9riaux \u00e9coresponsables<\/td>\n    <td>Usage th\u00e9rapeutique dans certains pays<\/td>\n  <\/tr>\n<\/table>\n\n<h2><span class=\"ez-toc-section\" id=\"Questions_frequemment_posees_sur_la_difference_entre_chanvre_et_cannabis\"><\/span>Questions fr\u00e9quemment pos\u00e9es sur la diff\u00e9rence entre chanvre et cannabis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<div itemscope itemtype=\"https:\/\/schema.org\/FAQPage\">\n  <div itemscope itemprop='mainEntity' itemtype='https:\/\/schema.org\/Question'>\n    <h3 itemprop='name'><span class=\"ez-toc-section\" id=\"Le_chanvre_est-il_legal_partout\"><\/span>Le chanvre est-il l\u00e9gal partout ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n    <div itemscope itemprop='acceptedAnswer' itemtype='https:\/\/schema.org\/Answer'><div itemprop='text'>\n      <p>La <strong>l\u00e9galit\u00e9 du chanvre<\/strong> d\u00e9pend de la <strong>teneur en THC<\/strong> fix\u00e9e par chaque pays. En France et dans la quasi-totalit\u00e9 des \u00c9tats europ\u00e9ens, seules les <strong>vari\u00e9t\u00e9s dont le taux de THC reste inf\u00e9rieur ou \u00e9gal \u00e0 0,3 %<\/strong> sont autoris\u00e9es \u00e0 la culture et \u00e0 la commercialisation.<\/p>\n      <ul>\n        <li>Seuil l\u00e9gal de THC obligatoire<\/li>\n        <li>Contr\u00f4le r\u00e9gulier des parcelles agricoles<\/li>\n        <li>Inscription des vari\u00e9t\u00e9s sur un catalogue officiel<\/li>\n      <\/ul>\n    <\/div><\/div>\n  <\/div>\n\n  <div itemscope itemprop='mainEntity' itemtype='https:\/\/schema.org\/Question'>\n    <h3 itemprop='name'><span class=\"ez-toc-section\" id=\"Est-ce_que_le_chanvre_contient_du_CBD\"><\/span>Est-ce que le chanvre contient du CBD ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n    <div itemscope itemprop='acceptedAnswer' itemtype='https:\/\/schema.org\/Answer'><div itemprop='text'>\n      <p>Oui, le <strong>chanvre<\/strong> est naturellement riche en <strong>cannabidiol (CBD)<\/strong>, surtout dans ses <strong>fleurs<\/strong> et ses <strong>feuilles<\/strong>. Ce compos\u00e9 b\u00e9n\u00e9ficie d&#8217;une popularit\u00e9 croissante pour ses effets relaxants et l&#8217;absence d\u2019effet planant.<\/p>\n      <ul>\n        <li>Extraits disponibles sous forme d\u2019huiles, <a href=\"https:\/\/www.cbd.fr\/173gelules-cbd\" data-internallinksmanager029f6b8e52c=\"8\" title=\"G\u00e9lule CBD\">g\u00e9lules<\/a>, cr\u00e8mes<\/li>\n        <li>Utilisation dans des <a href=\"https:\/\/www.cbd.fr\/150tisane-et-infusions-cbd\" data-internallinksmanager029f6b8e52c=\"13\" title=\"Infusion CBD\">infusions<\/a> ou dans la nourriture<\/li>\n      <\/ul>\n    <\/div><\/div>\n  <\/div>\n\n  <div itemscope itemprop='mainEntity' itemtype='https:\/\/schema.org\/Question'>\n    <h3 itemprop='name'><span class=\"ez-toc-section\" id=\"Pourquoi_utilise-t-on_le_terme_chanvre_industriel\"><\/span>Pourquoi utilise-t-on le terme chanvre industriel ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n    <div itemscope itemprop='acceptedAnswer' itemtype='https:\/\/schema.org\/Answer'><div itemprop='text'>\n      <p>Le terme &#8220;<strong>chanvre industriel<\/strong>&#8221; d\u00e9signe les <strong>vari\u00e9t\u00e9s exploit\u00e9es \u00e0 des fins non psychotropes<\/strong>, dans des activit\u00e9s telles que la fabrication textile, le b\u00e2timent ou encore l\u2019alimentaire. Leur <strong>faible teneur en THC<\/strong> emp\u00eache tout effet planant.<\/p>\n      <ul>\n        <li>Optimis\u00e9 pour la biomasse (fibres, graines, huiles)<\/li>\n        <li>S\u00e9lectionn\u00e9 pour respecter le seuil l\u00e9gal de THC<\/li>\n      <\/ul>\n      <table>\n        <tr><th>Usages principaux<\/th><th>Effet psychoactif<\/th><\/tr>\n        <tr><td>Industriel, bien-\u00eatre, alimentation<\/td><td>Non<\/td><\/tr>\n      <\/table>\n    <\/div><\/div>\n  <\/div>\n\n  <div itemscope itemprop='mainEntity' itemtype='https:\/\/schema.org\/Question'>\n    <h3 itemprop='name'><span class=\"ez-toc-section\" id=\"Comment_differencier_visuellement_le_chanvre_du_cannabis_recreatif\"><\/span>Comment diff\u00e9rencier visuellement le chanvre du cannabis r\u00e9cr\u00e9atif ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n    <div itemscope itemprop='acceptedAnswer' itemtype='https:\/\/schema.org\/Answer'><div itemprop='text'>\n      <p>Le <strong>chanvre<\/strong> pousse g\u00e9n\u00e9ralement plus haut, avec de longues <strong>tiges fines<\/strong> et peu de ramifications. Le <strong>cannabis r\u00e9cr\u00e9atif<\/strong> affiche une silhouette ramass\u00e9e, des feuilles plus larges et de nombreuses excroissances florales couvertes de <strong>r\u00e9sine<\/strong>.<\/p>\n      <ul>\n        <li>Diff\u00e9rence marqu\u00e9e dans la structure de la plante<\/li>\n        <li>Pr\u00e9sence ou absence de nombreux trichomes visibles<\/li>\n      <\/ul>\n    <\/div><\/div>\n  <\/div>\n<\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;14257&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Notez cet article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Quelle est la diff\u00e9rence entre le chanvre et le cannabis ?&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Notez cet article<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>La confusion persiste souvent entre le chanvre et le cannabis. Pourtant, derri\u00e8re ces deux noms se cachent des r\u00e9alit\u00e9s botaniques, culturelles et juridiques bien distinctes. Pour mieux comprendre ce qui s\u00e9pare vraiment ces deux plantes apparent\u00e9es, il faut plonger dans leurs caract\u00e9ristiques, leurs usages, leur teneur en THC ainsi que les subtilit\u00e9s de la l\u00e9galit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":14256,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[3337],"tags":[],"class_list":["post-14257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autour-du-cbd-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quelle est la diff\u00e9rence entre le chanvre et le cannabis ? - CBD Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31Quelle est la diff\u00e9rence entre le chanvre et le cannabis ? - CBD.fr \ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"La confusion persiste souvent entre le chanvre et le cannabis. Pourtant, derri\u00e8re ces deux noms se cachent des r\u00e9alit\u00e9s botaniques, culturelles et juridiques bien distinctes. Pour mieux comprendre ce qui s\u00e9pare vraiment ces deux plantes apparent\u00e9es, il faut plonger dans leurs caract\u00e9ristiques, leurs usages, leur teneur en THC ainsi que les subtilit\u00e9s de la l\u00e9galit\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/\" \/>\n<meta property=\"og:site_name\" content=\"CBD Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cbdfrr\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T12:54:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2025\/12\/quelle_est_la_diff_rence_entre_le_chanvre_et_le_cannabis.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1344\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Julien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quelle est la diff\u00e9rence entre le chanvre et le cannabis ? - CBD Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31Quelle est la diff\u00e9rence entre le chanvre et le cannabis ? - CBD.fr \ud83c\udf31","og_description":"La confusion persiste souvent entre le chanvre et le cannabis. Pourtant, derri\u00e8re ces deux noms se cachent des r\u00e9alit\u00e9s botaniques, culturelles et juridiques bien distinctes. Pour mieux comprendre ce qui s\u00e9pare vraiment ces deux plantes apparent\u00e9es, il faut plonger dans leurs caract\u00e9ristiques, leurs usages, leur teneur en THC ainsi que les subtilit\u00e9s de la l\u00e9galit\u00e9 [&hellip;]","og_url":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/","og_site_name":"CBD Blog","article_publisher":"https:\/\/www.facebook.com\/cbdfrr\/","article_published_time":"2026-05-07T12:54:25+00:00","og_image":[{"width":1344,"height":768,"url":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2025\/12\/quelle_est_la_diff_rence_entre_le_chanvre_et_le_cannabis.webp","type":"image\/webp"}],"author":"Julien","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julien","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#article","isPartOf":{"@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/"},"author":{"name":"Julien","@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/person\/d78b472d184ec8ae4135d454e3338c04"},"headline":"Quelle est la diff\u00e9rence entre le chanvre et le cannabis ?","datePublished":"2026-05-07T12:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/"},"wordCount":1271,"publisher":{"@id":"https:\/\/www.cbd.fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2025\/12\/quelle_est_la_diff_rence_entre_le_chanvre_et_le_cannabis.webp","articleSection":["Autour du CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/","url":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/","name":"Quelle est la diff\u00e9rence entre le chanvre et le cannabis ? - CBD Blog","isPartOf":{"@id":"https:\/\/www.cbd.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#primaryimage"},"image":{"@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2025\/12\/quelle_est_la_diff_rence_entre_le_chanvre_et_le_cannabis.webp","datePublished":"2026-05-07T12:54:25+00:00","breadcrumb":{"@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#primaryimage","url":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2025\/12\/quelle_est_la_diff_rence_entre_le_chanvre_et_le_cannabis.webp","contentUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2025\/12\/quelle_est_la_diff_rence_entre_le_chanvre_et_le_cannabis.webp","width":1344,"height":768,"caption":"Diff\u00e9rence entre Chanvre et Cannabis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cbd.fr\/blog\/quelle-est-la-difference-entre-le-chanvre-et-le-cannabis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/www.cbd.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Autour du CBD","item":"https:\/\/www.cbd.fr\/blog\/category\/autour-du-cbd-fr\/"},{"@type":"ListItem","position":3,"name":"Quelle est la diff\u00e9rence entre le chanvre et le cannabis ?"}]},{"@type":"WebSite","@id":"https:\/\/www.cbd.fr\/blog\/#website","url":"https:\/\/www.cbd.fr\/blog\/","name":"CBD Blog","description":"Le meilleur blog de CBD et du chanvre en France par CBD.fr","publisher":{"@id":"https:\/\/www.cbd.fr\/blog\/#organization"},"alternateName":"CBD.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cbd.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cbd.fr\/blog\/#organization","name":"CBD.fr","alternateName":"CBD.fr","url":"https:\/\/www.cbd.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2023\/01\/logo-cbd.png","contentUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2023\/01\/logo-cbd.png","width":215,"height":100,"caption":"CBD.fr"},"image":{"@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cbdfrr\/","https:\/\/www.instagram.com\/cbdfr\/","https:\/\/www.youtube.com\/@CBD_fr","https:\/\/www.linkedin.com\/company\/cbd-fr\/"],"description":"CBD.fr est le leaders fran\u00e7ais du bien-\u00eatre et du CBD, proposant une large gamme de produits \u00e0 base de chanvre rigoureusement s\u00e9lectionn\u00e9s. Expertise, qualit\u00e9 et p\u00e9dagogie sont au c\u0153ur de l\u2019exp\u00e9rience CBD.fr.","email":"support@cbd.fr","telephone":"0189720196","legalName":"CBD.fr","foundingDate":"2021-01-01","taxID":"760933","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/person\/d78b472d184ec8ae4135d454e3338c04","name":"Julien","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/58f2f1b1e71c329d0226efe2cc40174640e1757e077dac013c980f3ee43c73a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/58f2f1b1e71c329d0226efe2cc40174640e1757e077dac013c980f3ee43c73a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58f2f1b1e71c329d0226efe2cc40174640e1757e077dac013c980f3ee43c73a0?s=96&d=mm&r=g","caption":"Julien"},"description":"R\u00e9dacteur en chef sp\u00e9cialis\u00e9 en CBD Julien, n\u00e9 le 17 juillet 1978 en r\u00e9gion Parisienne, est un \u00e9minent r\u00e9dacteur et expert dans le domaine des produits \u00e0 base de CBD. Suite \u00e0 ses \u00e9tudes, Julien a d\u00e9velopp\u00e9 une passion pour les rem\u00e8des naturels, dont le CBD. En 2022, il int\u00e8gre l\u2019\u00e9quipe du site CBD.fr en qualit\u00e9 d\u2019expert et de contributeur r\u00e9gulier. Gr\u00e2ce \u00e0 son expertise scientifique et une \u00e9criture claire, Julien aide \u00e0 d\u00e9mystifier les aspects complexes du CBD, tout en mettant en lumi\u00e8re ses bienfaits et applications potentielles \u00e0 travers ses articles et participations \u00e0 des conf\u00e9rences.","honorificPrefix":"Mr","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"CBD.fr","url":"https:\/\/www.cbd.fr\/blog\/author\/redac-cbd\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts\/14257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/comments?post=14257"}],"version-history":[{"count":1,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts\/14257\/revisions"}],"predecessor-version":[{"id":14258,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts\/14257\/revisions\/14258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/media\/14256"}],"wp:attachment":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/media?parent=14257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/categories?post=14257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/tags?post=14257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}