{"id":18755,"date":"2026-02-13T18:09:11","date_gmt":"2026-02-13T17:09:11","guid":{"rendered":"https:\/\/www.cbd.fr\/blog\/?p=18755"},"modified":"2026-02-13T18:09:12","modified_gmt":"2026-02-13T17:09:12","slug":"o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade","status":"publish","type":"post","link":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/","title":{"rendered":"O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade?"},"content":{"rendered":"<p>O canabidiol, ou CBD, \u00e9 uma mol\u00e9cula derivada da cannabis que vem despertando crescente interesse devido \u00e0s suas in\u00fameras aplica\u00e7\u00f5es medicinais. No entanto, ainda existem d\u00favidas sobre seus potenciais efeitos no fluxo sangu\u00edneo. Este artigo tem como objetivo examinar em detalhes a rela\u00e7\u00e3o entre o CBD e a circula\u00e7\u00e3o sangu\u00ednea.<\/p>\n<h2><\/h2>\n<p>As Origens do CBD e seu Mecanismo de A\u00e7\u00e3o<\/p>\n<p>Derivado do c\u00e2nhamo, o CBD \u00e9 um dos muitos compostos presentes na planta Cannabis sativa. Ao contr\u00e1rio da cren\u00e7a popular, o CBD n\u00e3o possui propriedades psicoativas que possam levar ao v\u00edcio ou induzir a sensa\u00e7\u00e3o de euforia frequentemente associada ao <a href=\"https:\/\/www.cbd.fr\/198thccbd\" data-internallinksmanager029f6b8e52c=\"17\" title=\"thc - t\u00e9trahydrocannabinol\">THC<\/a> (tetrahidrocanabinol).<strong><\/strong>Pelo contr\u00e1rio, ele apresenta <a href=\"https:\/\/atelier-cbd.fr\/\">efeitos terap\u00eauticos interessantes,<\/a> como al\u00edvio da dor, redu\u00e7\u00e3o da ansiedade e atenua\u00e7\u00e3o dos sintomas relacionados a certas doen\u00e7as neurodegenerativas.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#O_CBDatua_em_particular_no_nosso_sistema_endocanabinoide_que_esta_envolvido_em_diversos_processos_biologicos_como_a_regulacao_do_humor_a_memoria_e_a_funcao_imunologica_Interacoes_com_outros_medicamentos\" >O CBDatua, em particular, no nosso sistema endocanabinoide, que est\u00e1 envolvido em diversos processos biol\u00f3gicos, como a regula\u00e7\u00e3o do humor, a mem\u00f3ria e a fun\u00e7\u00e3o imunol\u00f3gica. Intera\u00e7\u00f5es com outros medicamentos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#e_fundamentalmente_concebida_para_criar_um_coagulo_que_previna_hemorragias_e_promova_a_cicatrizacao_de_feridas_No_entanto_por_vezes_pode_levar_a_problemas_mais_graves_como_trombose_venosa_ou_arterial_formacao_anormal_de_coagulos_e_causar_problemas_cardiacos_como_o_AVC\" >\u00e9 fundamentalmente concebida para criar um co\u00e1gulo que previna hemorragias e promova a cicatriza\u00e7\u00e3o de feridas. No entanto, por vezes, pode levar a problemas mais graves, como trombose venosa ou arterial (forma\u00e7\u00e3o anormal de co\u00e1gulos) e causar problemas card\u00edacos, como o AVC.<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#Da_mesma_forma_alguns_relatos_anedoticos_sugerem_que_o_CBD_pode_ajudar_a_afinar_o_sangue_em_certas_circunstancias_como_quando_tomado_em_combinacao_com_outro_medicamento_que_tambem_possua_propriedades_anticoagulantes\" >Da mesma forma, alguns relatos aned\u00f3ticos sugerem que o CBD pode ajudar a afinar o sangue em certas circunst\u00e2ncias, como quando tomado em combina\u00e7\u00e3o com outro medicamento que tamb\u00e9m possua propriedades anticoagulantes.<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"O_CBDatua_em_particular_no_nosso_sistema_endocanabinoide_que_esta_envolvido_em_diversos_processos_biologicos_como_a_regulacao_do_humor_a_memoria_e_a_funcao_imunologica_Interacoes_com_outros_medicamentos\"><\/span><em>O CBD<\/em>atua, em particular, no nosso sistema endocanabinoide, que est\u00e1 envolvido em diversos processos biol\u00f3gicos, como a regula\u00e7\u00e3o do humor, a mem\u00f3ria e a fun\u00e7\u00e3o imunol\u00f3gica. Intera\u00e7\u00f5es com outros medicamentos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Como acontece com qualquer subst\u00e2ncia ativa, \u00e9 importante considerar as <strong>poss\u00edveis intera\u00e7\u00f5es entre o CBD e outros medicamentos<\/strong> ao utiliz\u00e1-lo. Alguns estudos destacaram uma intera\u00e7\u00e3o entre o CBD e as enzimas respons\u00e1veis \u200b\u200bpelo metabolismo de medicamentos no f\u00edgado, o que pode levar a um aumento ou diminui\u00e7\u00e3o do efeito de outros tratamentos administrados.<\/p>\n<h2><\/h2>\n<p>CBD e fluidez sangu\u00ednea: quais s\u00e3o as consequ\u00eancias?<\/p>\n<h3><\/h3>\n<p>Numerosos ensaios cl\u00ednicos e depoimentos atestam os efeitos positivos do CBD na sa\u00fade, particularmente na dor, ansiedade e inflama\u00e7\u00e3o cr\u00f4nica. No entanto, as informa\u00e7\u00f5es sobre seu impacto espec\u00edfico na composi\u00e7\u00e3o sangu\u00ednea ainda s\u00e3o incompletas e, \u00e0s vezes, contradit\u00f3rias. <i><\/i> Coagula\u00e7\u00e3o sangu\u00ednea e suas implica\u00e7\u00f5es<\/p>\n<p>Para melhor compreender a import\u00e2ncia desta quest\u00e3o, \u00e9 crucial lembrar o papel central desempenhado pela capacidade de coagula\u00e7\u00e3o do nosso sangue na manuten\u00e7\u00e3o de um delicado equil\u00edbrio entre os nossos diversos sistemas biol\u00f3gicos. <strong><\/strong>A coagula\u00e7\u00e3o<\/p>\n<h3><span class=\"ez-toc-section\" id=\"e_fundamentalmente_concebida_para_criar_um_coagulo_que_previna_hemorragias_e_promova_a_cicatrizacao_de_feridas_No_entanto_por_vezes_pode_levar_a_problemas_mais_graves_como_trombose_venosa_ou_arterial_formacao_anormal_de_coagulos_e_causar_problemas_cardiacos_como_o_AVC\"><\/span>\u00e9 fundamentalmente concebida para criar um co\u00e1gulo que previna hemorragias e promova a cicatriza\u00e7\u00e3o de feridas. No entanto, por vezes, pode levar a problemas mais graves, como trombose venosa ou arterial (forma\u00e7\u00e3o anormal de co\u00e1gulos) e causar problemas card\u00edacos, como o AVC.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><em>\u00c9, portanto, essencial estudar a fundo os efeitos do CBD neste mecanismo complexo e determinar se a mol\u00e9cula pode influenciar o fluxo sangu\u00edneo.<\/em><\/p>\n<p>Estudos atuais sobre o efeito do CBD na coagula\u00e7\u00e3o sangu\u00ednea<strong>Algumas pesquisas foram realizadas para compreender o potencial impacto do CBD na circula\u00e7\u00e3o sangu\u00ednea, mas ainda n\u00e3o permitiram conclus\u00f5es definitivas.<\/strong><br \/>\nDe acordo com algumas an\u00e1lises preliminares, o CBD pode ter um leve efeito anticoagulante em doses elevadas. Esta conclus\u00e3o baseia-se, em particular, em estudos in vitro, que demonstraram que o CBD pode inibir uma enzima (COX-2) que desempenha um papel central na forma\u00e7\u00e3o de co\u00e1gulos sangu\u00edneos quando tratada com plaquetas sangu\u00edneas isoladas. No entanto, esses resultados devem ser interpretados com cautela e requerem investiga\u00e7\u00e3o adicional, pois foram obtidos em condi\u00e7\u00f5es experimentais sem levar em considera\u00e7\u00e3o diversos fatores biol\u00f3gicos presentes em humanos.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Da_mesma_forma_alguns_relatos_anedoticos_sugerem_que_o_CBD_pode_ajudar_a_afinar_o_sangue_em_certas_circunstancias_como_quando_tomado_em_combinacao_com_outro_medicamento_que_tambem_possua_propriedades_anticoagulantes\"><\/span>Da mesma forma, alguns relatos aned\u00f3ticos sugerem que o CBD pode ajudar a afinar o sangue em certas circunst\u00e2ncias, como quando tomado em combina\u00e7\u00e3o com outro medicamento que tamb\u00e9m possua propriedades anticoagulantes.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>No entanto, \u00e9 importante notar que a maioria desses dados ainda se baseia em an\u00e1lises limitadas, insuficientemente documentadas ou n\u00e3o corroboradas por estudos cl\u00ednicos robustos e representativos. Nesse sentido, parece dif\u00edcil generalizar essas descobertas para fornecer uma resposta definitiva \u00e0 pergunta inicial.<\/p>\n<ul>\n<li><strong><\/strong> Quais precau\u00e7\u00f5es devem ser tomadas ao usar CBD?<\/li>\n<li> <strong>At\u00e9 que estudos mais rigorosos confirmem ou refutem a hip\u00f3tese de que o CBD tem efeito sobre a fluidez sangu\u00ednea, algumas recomenda\u00e7\u00f5es podem ser feitas:<\/strong> Consulte um m\u00e9dico<\/li>\n<li>antes de iniciar qualquer suplementa\u00e7\u00e3o com CBD, especialmente se voc\u00ea estiver tomando medicamentos anticoagulantes ou sofrer de dist\u00farbios de coagula\u00e7\u00e3o; <strong>Evite<\/strong> autodiagn\u00f3stico e automedica\u00e7\u00e3o<\/li>\n<li>sem supervis\u00e3o m\u00e9dica adequada;<\/li>\n<\/ul>\n<p>Esteja atento \u00e0<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;18755&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Notez cet article&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade?&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Notez cet article<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>O canabidiol, ou CBD, \u00e9 uma mol\u00e9cula derivada da cannabis que vem despertando crescente interesse devido \u00e0s suas in\u00fameras aplica\u00e7\u00f5es medicinais. No entanto, ainda existem d\u00favidas sobre seus potenciais efeitos no fluxo sangu\u00edneo. Este artigo tem como objetivo examinar em detalhes a rela\u00e7\u00e3o entre o CBD e a circula\u00e7\u00e3o sangu\u00ednea. As Origens do CBD e [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":11581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[936],"tags":[],"class_list":["post-18755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faq-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade? - CBD Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade? - CBD.fr \ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"O canabidiol, ou CBD, \u00e9 uma mol\u00e9cula derivada da cannabis que vem despertando crescente interesse devido \u00e0s suas in\u00fameras aplica\u00e7\u00f5es medicinais. No entanto, ainda existem d\u00favidas sobre seus potenciais efeitos no fluxo sangu\u00edneo. Este artigo tem como objetivo examinar em detalhes a rela\u00e7\u00e3o entre o CBD e a circula\u00e7\u00e3o sangu\u00ednea. As Origens do CBD e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/\" \/>\n<meta property=\"og:site_name\" content=\"CBD Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cbdfrr\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T17:09:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-13T17:09:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2024\/01\/le-cbd-et-ses-effets-sur-la-coagulation-sanguine-mythe-ou-realite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"832\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade? - CBD Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade? - CBD.fr \ud83c\udf31","og_description":"O canabidiol, ou CBD, \u00e9 uma mol\u00e9cula derivada da cannabis que vem despertando crescente interesse devido \u00e0s suas in\u00fameras aplica\u00e7\u00f5es medicinais. No entanto, ainda existem d\u00favidas sobre seus potenciais efeitos no fluxo sangu\u00edneo. Este artigo tem como objetivo examinar em detalhes a rela\u00e7\u00e3o entre o CBD e a circula\u00e7\u00e3o sangu\u00ednea. As Origens do CBD e [&hellip;]","og_url":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/","og_site_name":"CBD Blog","article_publisher":"https:\/\/www.facebook.com\/cbdfrr\/","article_published_time":"2026-02-13T17:09:11+00:00","article_modified_time":"2026-02-13T17:09:12+00:00","og_image":[{"width":1456,"height":832,"url":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2024\/01\/le-cbd-et-ses-effets-sur-la-coagulation-sanguine-mythe-ou-realite.jpg","type":"image\/jpeg"}],"author":"Julien","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julien","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#article","isPartOf":{"@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/"},"author":{"name":"Julien","@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/person\/d78b472d184ec8ae4135d454e3338c04"},"headline":"O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade?","datePublished":"2026-02-13T17:09:11+00:00","dateModified":"2026-02-13T17:09:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/"},"wordCount":714,"publisher":{"@id":"https:\/\/www.cbd.fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2024\/01\/le-cbd-et-ses-effets-sur-la-coagulation-sanguine-mythe-ou-realite.jpg","articleSection":["FAQ"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/","url":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/","name":"O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade? - CBD Blog","isPartOf":{"@id":"https:\/\/www.cbd.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#primaryimage"},"image":{"@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2024\/01\/le-cbd-et-ses-effets-sur-la-coagulation-sanguine-mythe-ou-realite.jpg","datePublished":"2026-02-13T17:09:11+00:00","dateModified":"2026-02-13T17:09:12+00:00","breadcrumb":{"@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#primaryimage","url":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2024\/01\/le-cbd-et-ses-effets-sur-la-coagulation-sanguine-mythe-ou-realite.jpg","contentUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2024\/01\/le-cbd-et-ses-effets-sur-la-coagulation-sanguine-mythe-ou-realite.jpg","width":1456,"height":832,"caption":"Le CBD et ses effets sur la coagulation sanguine : mythe ou r\u00e9alit\u00e9 ?, ingestion, mol\u00e9cule, prise"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cbd.fr\/blog\/o-cbd-e-seus-efeitos-na-coagulacao-sanguinea-mito-ou-realidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/www.cbd.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"FAQ","item":"https:\/\/www.cbd.fr\/blog\/category\/faq-pt\/"},{"@type":"ListItem","position":3,"name":"O CBD e seus efeitos na coagula\u00e7\u00e3o sangu\u00ednea: mito ou realidade?"}]},{"@type":"WebSite","@id":"https:\/\/www.cbd.fr\/blog\/#website","url":"https:\/\/www.cbd.fr\/blog\/","name":"CBD Blog","description":"Le meilleur blog de CBD et du chanvre en France par CBD.fr","publisher":{"@id":"https:\/\/www.cbd.fr\/blog\/#organization"},"alternateName":"CBD.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cbd.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cbd.fr\/blog\/#organization","name":"CBD.fr","alternateName":"CBD.fr","url":"https:\/\/www.cbd.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2023\/01\/logo-cbd.png","contentUrl":"https:\/\/www.cbd.fr\/blog\/wp-content\/uploads\/2023\/01\/logo-cbd.png","width":215,"height":100,"caption":"CBD.fr"},"image":{"@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cbdfrr\/","https:\/\/www.instagram.com\/cbdfr\/","https:\/\/www.youtube.com\/@CBD_fr","https:\/\/www.linkedin.com\/company\/cbd-fr\/"],"description":"CBD.fr est le leaders fran\u00e7ais du bien-\u00eatre et du CBD, proposant une large gamme de produits \u00e0 base de chanvre rigoureusement s\u00e9lectionn\u00e9s. Expertise, qualit\u00e9 et p\u00e9dagogie sont au c\u0153ur de l\u2019exp\u00e9rience CBD.fr.","email":"support@cbd.fr","telephone":"0189720196","legalName":"CBD.fr","foundingDate":"2021-01-01","taxID":"760933","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.cbd.fr\/blog\/#\/schema\/person\/d78b472d184ec8ae4135d454e3338c04","name":"Julien","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/58f2f1b1e71c329d0226efe2cc40174640e1757e077dac013c980f3ee43c73a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/58f2f1b1e71c329d0226efe2cc40174640e1757e077dac013c980f3ee43c73a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58f2f1b1e71c329d0226efe2cc40174640e1757e077dac013c980f3ee43c73a0?s=96&d=mm&r=g","caption":"Julien"},"description":"R\u00e9dacteur en chef sp\u00e9cialis\u00e9 en CBD Julien, n\u00e9 le 17 juillet 1978 en r\u00e9gion Parisienne, est un \u00e9minent r\u00e9dacteur et expert dans le domaine des produits \u00e0 base de CBD. Suite \u00e0 ses \u00e9tudes, Julien a d\u00e9velopp\u00e9 une passion pour les rem\u00e8des naturels, dont le CBD. En 2022, il int\u00e8gre l\u2019\u00e9quipe du site CBD.fr en qualit\u00e9 d\u2019expert et de contributeur r\u00e9gulier. Gr\u00e2ce \u00e0 son expertise scientifique et une \u00e9criture claire, Julien aide \u00e0 d\u00e9mystifier les aspects complexes du CBD, tout en mettant en lumi\u00e8re ses bienfaits et applications potentielles \u00e0 travers ses articles et participations \u00e0 des conf\u00e9rences.","honorificPrefix":"Mr","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"CBD.fr","url":"https:\/\/www.cbd.fr\/blog\/author\/redac-cbd\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts\/18755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/comments?post=18755"}],"version-history":[{"count":1,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts\/18755\/revisions"}],"predecessor-version":[{"id":18756,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/posts\/18755\/revisions\/18756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/media\/11581"}],"wp:attachment":[{"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/media?parent=18755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/categories?post=18755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cbd.fr\/blog\/wp-json\/wp\/v2\/tags?post=18755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}